{"id":1558,"date":"2024-09-01T00:01:53","date_gmt":"2024-08-31T22:01:53","guid":{"rendered":"https:\/\/www.sionaeroport.ch\/carburant\/"},"modified":"2024-12-27T16:59:30","modified_gmt":"2024-12-27T15:59:30","slug":"fuel","status":"publish","type":"page","link":"https:\/\/www.sionaeroport.ch\/en\/fuel\/","title":{"rendered":"Fuel Policy"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-xs-0 col-sm-0 col-md-4 col-lg-6\"><\/div>\n<p>\n        <div class=\"db-widget col-xs-6 col-sm-6 col-md-4 col-lg-3\">\n            <div class=\"main-col\">\n                <div class=\"widget-content border-red\">\n                    <!-- START STATIC CONTENT -->\n                    <div>\n                      <div id=\"w-fuel\" class=\"widget-item fixed active\">\n                              <div class=\"text title\">\n                                  <span class=\"lbl\"><b>Prix du carburant<\/b><\/span>\n                              <\/div>\n\n                              <div class=\"text sub\">\n                                  <span class=\"lbl\"><small>(CHF\/LITER)<\/small><\/span>\n                              <\/div>\n\n                              <div class=\"tbl\">\n                                  <div class=\"row title text-left\">\n                                      <div class=\"col-xs-4 col\">\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        Full Price\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        Duty Free\n                                      <\/div>\n                                  <\/div>\n                                  <div class=\"row fuel text-left\">\n                                      <div class=\"col-xs-4 col\">\n                                        AVGAS\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">2.70<\/span>\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">1.85<\/span>\n                                      <\/div>\n                                  <\/div>\n\n                                  <div class=\"row fuel text-left\">\n                                      <div class=\"col-xs-4 col\">\n                                        JET A1\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">2.43<\/span>\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">1.61<\/span>\n                                      <\/div>\n                                  <\/div>\n\n                                  <div class=\"row fuel text-left\">\n                                      <div class=\"col-xs-4 col\">\n                                        UL 91\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">2.35<\/span>\n                                      <\/div>\n                                      <div class=\"col-xs-4 col\">\n                                        <span class=\"value\">-<\/span>\n                                      <\/div>\n                                  <\/div>\n                              <\/div>\n                              <div class=\"text freq\">\n                                  <span class=\"lbl\">+ VAT: 8.1% (2026)<\/span>\n                              <\/div>\n                          <\/div>\n                      <\/div>\n                      <!-- END STATIC CONTENT -->                      \n                <\/div>\n            <\/div>\n        <\/div>        <div class=\"db-widget col-xs-6 col-sm-6 col-md-4 col-lg-3\">\n            <div class=\"main-col\" style=\"height:105px;\">\n                <div class=\"widget-content border-green\">\n                  <!-- START STATIC CONTENT -->\n                    <div>\n                      <div id=\"w-saf\" class=\"widget-item fixed active\">\n\n                        <div class=\"text title\">\n                          <span class=\"lbl\">\n                            <b>Prix du SAF <!--small style=\"font-weight:normal;font-size:60%;\">(CHF\/LITER)<\/small--><\/b>\n                            <img decoding=\"async\" src=\"https:\/\/www.sionaeroport.ch\/wp-content\/uploads\/2024\/04\/SAF_transparent-150x150.png\" style=\"height:40px; float:right;\" \/>\n                          <\/span>\n                        <\/div>\n\n                        <div class=\"text sub\">\n                          <span class=\"lbl\"><small>(CHF\/LITER)<\/small><\/span>\n                        <\/div>\n\n                        <div class=\"tbl\">\n                          <div class=\"row title text-left\">\n                              <div class=\"col-xs-4 col\"><\/div>\n                              <div class=\"col-xs-4 col\">Full Price<\/div>\n                              <div class=\"col-xs-4 col\">Duty Free<\/div>\n                          <\/div>\n                          \n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">SAF<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\"><\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\"><\/span><\/div>\n                          <\/div>\n                          \n                          <!--div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">2%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf2_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf2_duty_option}<\/span><\/div>\n                          <\/div>\n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">5%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf5_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf5_duty_option}<\/span><\/div>\n                          <\/div>\n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">10%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf10_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf10_duty_option}<\/span><\/div>\n                          <\/div>\n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">15%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf15_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf15_duty_option}<\/span><\/div>\n                          <\/div>\n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">20%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf20_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf20_duty_option}<\/span><\/div>\n                          <\/div>\n                          <div class=\"row fuel text-left\">\n                            <div class=\"col-xs-4 col\">30%<\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf30_full_option}<\/span><\/div>\n                            <div class=\"col-xs-4 col\"><span class=\"value\">{saf30_duty_option}<\/span><\/div>\n                          <\/div-->\n                          \n                        <\/div>\n                        <div class=\"text freq\">\n                          <span class=\"lbl\">+ VAT: 8.1% (2026)<\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <!-- END STATIC CONTENT -->\n                <\/div>\n            <\/div>\n        <\/div>\n\n\n<\/p><\/div>\n<h1 class=\"red\"><strong>Maximize Your Benefits with a Fuel Account!<\/strong><\/h1>\n<p>Dear Frequent Operators of Sion Airport,<\/p>\n<p>&nbsp;<\/p>\n<p>We are excited to introduce a new opportunity for our most valued operators: the ability to open a dedicated fuel account with us directly at Sion Airport.<\/p>\n<p>&nbsp;<\/p>\n<p>With a fuel account, you can enjoy exclusive advantages tailored to your operational needs. These benefits increase based on the volume of fuel you use, allowing you to maximize your savings and streamline your operations.<\/p>\n<p>&nbsp;<\/p>\n<p>Key Benefits of Opening a Fuel Account:<\/p>\n<ul>\n<li><strong>Tiered Discounts<\/strong>: Unlock greater savings as you purchase more fuel.<\/li>\n<li><strong>Detailed Reporting<\/strong>: Receive comprehensive fuel usage reports to help manage your expenses efficiently.<\/li>\n<li><strong>Flexible Payment Options<\/strong>: Enjoy the convenience of tailored payment plans.<br \/>\nTo give you a clearer understanding, we&#8217;ve attached examples of the official documents detailing the terms and conditions, as well as the advantages of each tier.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Don&#8217;t miss out on this opportunity to enhance your operations at Sion Airport.<\/p>\n<p>&nbsp;<\/p>\n<p>For more information, please contact our team at aeroport@sion.ch or, to get started, you can register online via the account opening form:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.sionaeroport.ch\/en\/fuel\/account-opening-form\/\" class=\"btn btn-danger\">Go to the account opening form<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>We look forward to continuing to support your operations at Sion Airport.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-xs-6 col-lg-3 col text-center\">\n        <a href=\"https:\/\/www.sionaeroport.ch\/wp-content\/uploads\/2024\/12\/LSGS_Fuel_tariffs_2025.pdf\" target=\"_blank\" class=\"download\" rel=\"noopener\">\n          <img decoding=\"async\" class=\"icon\" src=\"https:\/\/www.sionaeroport.ch\/wp-content\/themes\/sionairport_V2_11072017\/src\/assets\/icon-pdf.png\">\n          <p>Guidelines and tariffs for aviation fuels at Sion Airport 2025<\/p>\n          <img decoding=\"async\" class=\"arrow\" src=\"https:\/\/www.sionaeroport.ch\/wp-content\/themes\/sionairport_V2_11072017\/src\/assets\/icon-arrow-down.png\">\n        <\/a>\n      <\/div>\n<div class=\"col-xs-6 col-lg-3 col text-center\">\n        <a href=\"https:\/\/www.sionaeroport.ch\/wp-content\/uploads\/2024\/08\/LSGS_Convention_carburant_2024_EXEMPLE_EN.pdf\" target=\"_blank\" class=\"download\" rel=\"noopener\">\n          <img decoding=\"async\" class=\"icon\" src=\"https:\/\/www.sionaeroport.ch\/wp-content\/themes\/sionairport_V2_11072017\/src\/assets\/icon-pdf.png\">\n          <p>Example of a fuelling agreement<\/p>\n          <img decoding=\"async\" class=\"arrow\" src=\"https:\/\/www.sionaeroport.ch\/wp-content\/themes\/sionairport_V2_11072017\/src\/assets\/icon-arrow-down.png\">\n        <\/a>\n      <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Maximize Your Benefits with a Fuel Account! Dear Frequent Operators of Sion Airport, &nbsp; We are excited to introduce a new opportunity for our most valued operators: the ability to open a dedicated fuel account with us directly at Sion Airport. &nbsp; With a fuel account, you can enjoy exclusive advantages tailored to your operational [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-default.php","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:55:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"sections"},"_links":{"self":[{"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/pages\/1558"}],"collection":[{"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/comments?post=1558"}],"version-history":[{"count":7,"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/pages\/1558\/revisions"}],"predecessor-version":[{"id":1653,"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/pages\/1558\/revisions\/1653"}],"wp:attachment":[{"href":"https:\/\/www.sionaeroport.ch\/en\/wp-json\/wp\/v2\/media?parent=1558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}